{"id":334,"date":"2024-03-08T20:08:18","date_gmt":"2024-03-08T19:08:18","guid":{"rendered":"https:\/\/corderie-mansas.fr\/blog-corderiemansas\/?p=334"},"modified":"2025-09-10T14:39:13","modified_gmt":"2025-09-10T12:39:13","slug":"lexique-du-cordage","status":"publish","type":"post","link":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/2024\/03\/08\/lexique-du-cordage\/","title":{"rendered":"Lexique du cordage"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>\u00c9pissure, drisse, \u00e9cheveau&#8230; Parler de cordes, c&rsquo;est tout un langage. Pr\u00e9cis, technique, parfois m\u00e9connu, mais qui en dit long sur les secrets de fabrication, les qualit\u00e9s et l&rsquo;usage de chaque cordage. Pour vous aider \u00e0 le d\u00e9crypter et \u00e0 faire les bons choix, voici une liste (non exhautive) des termes les plus couramment employ\u00e9s. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Tour d&rsquo;horizon des expressions du cordage, de A \u00e0 Z<\/h5>\n\n\n\n<p class=\"has-small-font-size\"><strong>Abrasion<\/strong> (SYN. <em>ragage, frottement, friction<\/em>) : Usage de la corde par friction. <br><em>Les cordes tress\u00e9es sont g\u00e9n\u00e9ralement plus r\u00e9sistantes \u00e0 l\u2019abrasion que les cordes torsad\u00e9es.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Allongement<\/strong> (SYN. <em>\u00e9lasticit\u00e9, fluage<\/em>) : Variation provisoire ou permanente de la longueur d\u2019une corde provoqu\u00e9e par les tensions exerc\u00e9es. <br><em>Le coefficient d\u2019allongement d\u2019une corde varie selon la mati\u00e8re premi\u00e8re et le type de tressage\/commettage. Il peut \u00eatre limit\u00e9 par un proc\u00e9d\u00e9 de pr\u00e9-\u00e9tirage et de thermofixage.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Allongement \u00e0 la rupture<\/strong> (SYN. <em>ductilit\u00e9<\/em>) : Capacit\u00e9 maximale d\u2019allongement d\u2019une corde. <br><em>Un fort allongement \u00e0 la rupture procure une meilleure capacit\u00e9 d\u2019absorption des chocs qui surtendent la corde. Les fibres de corde ayant le plus grand allongement \u00e0 la rupture sont le caoutchouc et le nylon (polyamide).<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c2me d\u2019une corde torsad\u00e9e<\/strong> : Cordon ins\u00e9r\u00e9 entre les torons pour renforcer une corde torsad\u00e9e ou un c\u00e2ble acier.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c2me d\u2019une drisse<\/strong> : Cordon \u00e0 l&rsquo;int\u00e9rieur de la gaine d\u2019une corde tress\u00e9e pour lui permettre d&rsquo;\u00eatre ronde et renforc\u00e9e. <br><em>Ind\u00e9pendante de la gaine ext\u00e9rieure, elle peut \u00eatre retir\u00e9e manuellement. L\u2019\u00e2me peut \u00eatre tress\u00e9e ou parall\u00e8le.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c2me parall\u00e8le<\/strong> : \u00c2me constitu\u00e9e de fils align\u00e9s.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c2me tress\u00e9e<\/strong> : \u00c2me constitu\u00e9e de fils tress\u00e9s. <br><em>Une tresse constitu\u00e9e d\u2019une \u00e2me tress\u00e9e peut se dire \u201cdouble tresse\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Au m\u00e8tre<\/strong> : Choix libre de la longueur d\u2019une corde selon le nombre de m\u00e8tres souhait\u00e9s. Une corde \u201cau m\u00e8tre\u201d est livr\u00e9e en un seul tenant.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Bobine<\/strong> : Cylindre autour duquel s\u2019enroule une corde. \u00c0 ne pas confondre avec une \u201ccouronne\u201d ou un \u201c\u00e9cheveau\u201d.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Bout<\/strong> (SYN. <em>corde, drisse, garcette<\/em>) : Expression d\u00e9signant une corde dans le milieu marin.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Commettage<\/strong> : Action de r\u00e9unir les torons par torsion pour former une cordage uni et r\u00e9gulier. <br><em>Le commettage en \u201cS\u201d se fait vers la gauche, le commettage en \u201cZ\u201d se fait vers la droite. Sauf exception, le sens de commettage n\u2019impacte pas l\u2019utilisation d\u2019une corde.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Corde torsad\u00e9e<\/strong> (SYN.<em> corde toronn\u00e9e, corde c\u00e2bl\u00e9e, aussi\u00e8re<\/em>) : Corde form\u00e9e de trois ou quatre torons commis afin de former un cordage uni et r\u00e9gulier. S\u2019oppose \u00e0 la corde tress\u00e9e.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Cordon<\/strong> (SYN. <em>cordelette, ficelle<\/em>) : Corde tress\u00e9e ou torsad\u00e9e d\u2019un diam\u00e8tre g\u00e9n\u00e9ralement inf\u00e9rieur \u00e0 5mm.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Couronne<\/strong> : Conditionnement de la corde sans utilisation de bobine. <br><em>\u00c0 ne pas confondre avec une \u201cbobine\u201d ou un \u201c\u00e9cheveau\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Densit\u00e9<\/strong> (SYN. <em>flottabilit\u00e9<\/em>) : En comparant le poids volum\u00e9trique d\u2019une fibre \u00e0 celui de l\u2019eau, la densit\u00e9 indique la flottabilit\u00e9 d\u2019une corde. <br><em>Une corde est flottante si ses fibres ont une densit\u00e9 inf\u00e9rieure \u00e0 1. Seules les fibres de polypropyl\u00e8ne (0,91) et de poly\u00e9thyl\u00e8ne (0,92) sont flottantes.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Diam\u00e8tre<\/strong> (SYN.<em> calibre, \u00e9paisseur<\/em>) : Largeur d\u2019un cordage.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Drisse<\/strong> : Appellation maritime d\u2019une corde tress\u00e9e g\u00e9n\u00e9ralement utilis\u00e9e pour hisser une vergue, une corne ou une voile.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c9cheveau<\/strong> : Conditionnement de la corde en vrac lorsqu\u2019une corde \u00e0 \u00e9t\u00e9 d\u00e9roul\u00e9e d\u2019une bobine pour \u00eatre coup\u00e9e au m\u00e8tre.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c9lasticit\u00e9<\/strong> (SYN. <em>allongement<\/em>) : Allongement provisoire provoqu\u00e9e par une tension exerc\u00e9e sur un cordage.<br><em>\u00c0 ne pas confondre avec le fluage qui est une tension permanente.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>\u00c9pissure<\/strong> (SYN. <em>\u0153il<\/em>) : Tressage des fils constituant un \u0153il au bout d\u2019une corde. <br><em>L\u2019\u00e9pissure peut \u00eatre r\u00e9alis\u00e9e sur une corde torsad\u00e9e ou tress\u00e9e. Elle peut \u00eatre renforc\u00e9e par une cosse c\u0153ur. Par s\u00e9curit\u00e9, elle doit \u00eatre r\u00e9alis\u00e9e par un sp\u00e9cialiste.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fluage<\/strong> (SYN. <em>allongement<\/em>) : Allongement irr\u00e9versible provoqu\u00e9 par les tensions exerc\u00e9es sur un cordage.<br><em>\u00c0 ne pas confondre avec l\u2019\u00e9lasticit\u00e9 qui est une tension provisoire.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Toron<\/strong> (SYN.<em> brin, c\u00e2ble<\/em>) : Faisceau de fils de caret constituant un c\u00e2ble. <br><em>Une corde torsad\u00e9e est g\u00e9n\u00e9ralement constitu\u00e9e de trois ou quatre torons commis par torsion.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fibre<\/strong> : Fil tr\u00e8s fin constituant la mati\u00e8re premi\u00e8re d\u2019une corde.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Fil de caret<\/strong> : Faisceau de fibres constituant un petit c\u00e2ble. <br><em>Trois fils de caret doivent g\u00e9n\u00e9ralement \u00eatre assembl\u00e9s par torsion pour former un toron.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Gaine<\/strong> : Partie ext\u00e9rieure d\u2019une corde tress\u00e9e.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Ganse<\/strong> (SYN<em>. tresse, cordon<\/em>) : Type de corde en coton tress\u00e9 utilis\u00e9 pour l&rsquo;artisanat.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Garcette<\/strong> (SYN. <em>bout, corde, ficelle, drisse, cordeau<\/em>) : Corde synth\u00e9tique d\u2019un diam\u00e8tre g\u00e9n\u00e9ralement inf\u00e9rieur \u00e0 5mm utilis\u00e9e pour faire tous types de petits travaux sur un navire.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>R\u00e9sistance de rupture<\/strong> : Capacit\u00e9 de traction d\u2019une corde lorsqu\u2019elle est neuve, statique, droite, sans n\u0153uds et sans \u00e9pissure. Une tol\u00e9rance de +\/- 7% est toujours appliqu\u00e9e pour les r\u00e9sistances de rupture d\u2019une corde. Par s\u00e9curit\u00e9, il ne faut pas utiliser plus de 80% de la charge de rupture d\u2019une corde lorsqu\u2019elle est neuve.<br>Exprim\u00e9e en KG, elle d\u00e9signe la capacit\u00e9 de tension \u00e0 l\u2019arr\u00eat (poids); tandis qu\u2019exprim\u00e9e en d\u00e9canewton (DaN), elle d\u00e9signe la capacit\u00e9 de tension en mouvement (poids x vitesse). L\u2019utilisation d\u2019une corde att\u00e9nue m\u00e9caniquement sa r\u00e9sistance de rupture. Les principaux facteurs d\u2019att\u00e9nuation de la r\u00e9sistance d\u2019une corde sont : humidit\u00e9, rayons UV, chaleur, gel, abrasion, n\u0153uds, \u00e9pissure et agents chimiques.<br><em>\u00c0 ne pas confondre avec la Charge Maximale d\u2019Utilisation (CMU).<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>R\u00e9sistance r\u00e9siduelle<\/strong> : Exprim\u00e9e en pourcentage, c\u2019est la r\u00e9sistance de rupture d\u2019une corde calcul\u00e9e en tenant compte d\u2019une courbe ou d\u2019un n\u0153ud. <br><em>De mani\u00e8re g\u00e9n\u00e9rale, plus la courbe est \u00e9lev\u00e9e, plus la r\u00e9sistance r\u00e9siduelle est faible. La r\u00e9sistance r\u00e9siduelle d&rsquo;un n\u0153ud varie selon son niveau \u00ab\u00a0d&rsquo;\u00e9tranglement\u00a0\u00bb de la corde lorsqu&rsquo;elle est sous tension.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Sandow<\/strong> (SYN. <em>tendeur, corde \u00e9lastique<\/em>) : Corde tress\u00e9e \u00e9lastique g\u00e9n\u00e9ralement constitu\u00e9e d\u2019une \u00e2me en caoutchouc et d\u2019une gaine en polyester ou polypropyl\u00e8ne.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Touret<\/strong> : Grande bobine en bois g\u00e9n\u00e9ralement utilis\u00e9e pour les conditionnement tr\u00e8s lourds. <br><em>Le touret est un objet qui peut \u00eatre d\u00e9tourn\u00e9 pour r\u00e9aliser une table basse. Sauf exception, la Corderie Mansas n\u2019utilise pas de touret pour le conditionnement des cordages.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Tresse<\/strong> (SYN. <em>corde tress\u00e9e, drisse, ganse<\/em>) : Entrelacement de fuseaux formant une gaine continue et r\u00e9guli\u00e8re. <br><em>La tresse peut \u00eatre creuse ou renforc\u00e9e par une \u00e2me.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9pissure, drisse, \u00e9cheveau&#8230; Parler de cordes, c&rsquo;est tout un langage. Tour d&rsquo;horizon des expressions du cordage de A \u00e0 Z<\/p>\n","protected":false},"author":2,"featured_media":437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/posts\/334"}],"collection":[{"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":15,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"predecessor-version":[{"id":619,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/posts\/334\/revisions\/619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/media\/437"}],"wp:attachment":[{"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.corderie-mansas.fr\/blog-corderiemansas\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}